{"id":27,"date":"2012-11-01T22:59:37","date_gmt":"2012-11-01T22:59:37","guid":{"rendered":"http:\/\/wiki2.professionearchitetto.it\/anteprima-dwg-e-pat-da-gestione-risorse\/"},"modified":"2012-11-01T22:59:37","modified_gmt":"2012-11-01T22:59:37","slug":"anteprima-dwg-e-pat-da-gestione-risorse","status":"publish","type":"post","link":"https:\/\/www.professionearchitetto.it\/wiki\/anteprima-dwg-e-pat-da-gestione-risorse\/","title":{"rendered":"Anteprima DWG e PAT da gestione risorse"},"content":{"rendered":"<p><b>CadXplorer <\/b>si integra con gestione risorse di Windows, permette l&#8217;anteprima dei seguenti tipi di file&#160;: <\/p> <ul><li>.DWG <\/li><li>.PAT(Hatch) con possibilit\u00e0 di EDITOR <\/li><li>.SHX (Font &#8211; Shape) <\/li><li>.SLD (Slide) <\/li><li>.SLB (Libreria di Slide) <\/li><\/ul> <p><a rel=\"nofollow\" target=\"_blank\" class=\"external free\" href=\"http:\/\/www.cadwerx.net\/\">http:\/\/www.cadwerx.net\/<\/a> <\/p><p>Allego 3 file con immagini di esempio <\/p> <ul><li><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"\/wiki\/images\/uploads\/raf\/1_immagini_CadXplorer.zip\">1_immagini_CadXplorer.zip<\/a> <\/li><li><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"\/wiki\/images\/uploads\/raf\/2_immagini_CadXplorer.zip\">2_immagini_CadXplorer.zip<\/a> <\/li><li><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"\/wiki\/images\/uploads\/raf\/3_immagini_CadXplorer.zip\">3_immagini_CadXplorer.zip<\/a> <\/li><\/ul> <p>raf <\/p> <!-- Tidy found serious XHTML errors -->  <!--  NewPP limit report Preprocessor node count: 1\/1000000 Post-expand include size: 0\/2097152 bytes Template argument size: 0\/2097152 bytes Expensive parser function count: 0\/100 -->  <!-- Saved in parser cache with key wikidb-mw_:pcache:idhash:41-0!*!*!*!*!*!* and timestamp 20130404092333 --> ","protected":false},"excerpt":{"rendered":"<p>CadXplorer si integra con gestione risorse di Windows, permette l&#8217;anteprima dei seguenti tipi di file&#160;: .DWG .PAT(Hatch) con possibilit\u00e0 di EDITOR .SHX (Font &#8211; Shape) .SLD (Slide) .SLB (Libreria di Slide) http:\/\/www.cadwerx.net\/ Allego 3 file con immagini di esempio 1_immagini_CadXplorer.zip 2_immagini_CadXplorer.zip 3_immagini_CadXplorer.zip raf<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-27","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-w"},"views":4987,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/comments?post=27"}],"version-history":[{"count":0,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/27\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/media?parent=27"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/categories?post=27"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/tags?post=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}