{"id":359,"date":"2010-06-14T18:20:06","date_gmt":"2010-06-14T16:20:06","guid":{"rendered":"http:\/\/wiki2.professionearchitetto.it\/lana-di-roccia\/"},"modified":"2015-07-19T17:55:16","modified_gmt":"2015-07-19T15:55:16","slug":"lana-di-roccia","status":"publish","type":"post","link":"https:\/\/www.professionearchitetto.it\/wiki\/lana-di-roccia\/","title":{"rendered":"Lana di roccia"},"content":{"rendered":"<h2> <span class=\"mw-headline\" id=\"Cos.27.C3.A8_la_.22lana_di_roccia.22_e_a_cosa_serve\">Cos&#8217;\u00e8 la &#8220;lana di roccia&#8221; e a cosa serve<\/span><\/h2> <p>La lana di roccia \u00e8 un materiale naturale, altamente termoisolante, e per la sua struttura a celle aperte \u00e8 anche fonoassorbente. <\/p><p>Di origine vulcanica \u00e8 stato scoperto per la prima volta nelle isole Hawaii. <\/p><p>E&#8217; usata per isolare termicamente e acusticamente edifici o singoli ambienti. <\/p><p><br \/> <\/p> <h2> <span class=\"mw-headline\" id=\"Collegamenti_esterni\">Collegamenti esterni<\/span><\/h2> <ul><li><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"http:\/\/www.rockwool.it\">www.rockwool.it<\/a> schede tecniche approfondite <\/li><li><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"http:\/\/www.passive-on.org\/it\/\">www.passive-on.org\/it\/<\/a> Il Progetto Passive-On <\/li><\/ul>  <!-- Tidy found serious XHTML errors -->  <!--  NewPP limit report Preprocessor node count: 6\/1000000 Post-expand include size: 0\/2097152 bytes Template argument size: 0\/2097152 bytes Expensive parser function count: 0\/100 -->  <!-- Saved in parser cache with key wikidb-mw_:pcache:idhash:253-0!*!*!!*!*!* and timestamp 20130404140102 --> ","protected":false},"excerpt":{"rendered":"<p>Cos&#8217;\u00e8 la &#8220;lana di roccia&#8221; e a cosa serve La lana di roccia \u00e8 un materiale naturale, altamente termoisolante, e per la sua struttura a celle aperte \u00e8 anche fonoassorbente. Di origine vulcanica \u00e8 stato scoperto per la prima volta nelle isole Hawaii. E&#8217; usata per isolare termicamente e acusticamente edifici o singoli ambienti. Collegamenti [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[3,8,59,9],"class_list":["post-359","post","type-post","status-publish","format-standard","category-w","tag-archibolario","tag-esame-di-stato-architettura","tag-fisica-tecnica","tag-tecnologia"],"views":11027,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/comments?post=359"}],"version-history":[{"count":0,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/359\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/media?parent=359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/categories?post=359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/tags?post=359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}