{"id":379,"date":"2011-05-30T19:16:12","date_gmt":"2011-05-30T19:16:12","guid":{"rendered":"http:\/\/wiki2.professionearchitetto.it\/link-per-tutorial\/"},"modified":"2011-05-30T19:16:12","modified_gmt":"2011-05-30T19:16:12","slug":"link-per-tutorial","status":"publish","type":"post","link":"https:\/\/www.professionearchitetto.it\/wiki\/link-per-tutorial\/","title":{"rendered":"Link per tutorial"},"content":{"rendered":"<p>ciao amici o colleghi o amici colleghi o altro&#8230;. <\/p><p>visitatevi questo sito <\/p><p><a rel=\"nofollow\" target=\"_blank\" class=\"external free\" href=\"http:\/\/www.renderosity.com\/tut.ez?Form.sess_id=21452984&amp;Form.sess_key=1098290288\">http:\/\/www.renderosity.com\/tut.ez?Form.sess_id=21452984&amp;Form.sess_key=1098290288<\/a> <\/p><p>tutorial per tutti i software&#8230;.saluti <\/p><p>Aggiungo un altro elenco di link&#8230; per chi ha voglia di navigare!!!! <\/p><p><a rel=\"nofollow\" target=\"_blank\" class=\"external free\" href=\"http:\/\/www.treddi.com\/forum\/index.php?showtopic=24\">http:\/\/www.treddi.com\/forum\/index.php?showtopic=24<\/a>  <\/p><p><a rel=\"nofollow\" target=\"_blank\" class=\"external free\" href=\"http:\/\/www.tutorialing.com\/\">http:\/\/www.tutorialing.com\/<\/a> <\/p><p>modellate gente, modellate! <\/p><p>ciao ciao <\/p><p>nico, steppi, nico <\/p> <!-- Tidy found serious XHTML errors -->  <!--  NewPP limit report Preprocessor node count: 1\/1000000 Post-expand include size: 0\/2097152 bytes Template argument size: 0\/2097152 bytes Expensive parser function count: 0\/100 -->  <!-- Saved in parser cache with key wikidb-mw_:pcache:idhash:770-0!*!*!*!*!*!* and timestamp 20130404090317 --> ","protected":false},"excerpt":{"rendered":"<p>ciao amici o colleghi o amici colleghi o altro&#8230;. visitatevi questo sito http:\/\/www.renderosity.com\/tut.ez?Form.sess_id=21452984&amp;Form.sess_key=1098290288 tutorial per tutti i software&#8230;.saluti Aggiungo un altro elenco di link&#8230; per chi ha voglia di navigare!!!! http:\/\/www.treddi.com\/forum\/index.php?showtopic=24 http:\/\/www.tutorialing.com\/ modellate gente, modellate! ciao ciao nico, steppi, nico<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-379","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-w"},"views":1863,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/comments?post=379"}],"version-history":[{"count":0,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/379\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/media?parent=379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/categories?post=379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/tags?post=379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}