{"id":506,"date":"2010-07-23T18:31:08","date_gmt":"2010-07-23T18:31:08","guid":{"rendered":"http:\/\/wiki2.professionearchitetto.it\/qual-e-lo-schema-statico-di-una-capriata\/"},"modified":"2010-07-23T18:31:08","modified_gmt":"2010-07-23T18:31:08","slug":"qual-e-lo-schema-statico-di-una-capriata","status":"publish","type":"post","link":"https:\/\/www.professionearchitetto.it\/wiki\/qual-e-lo-schema-statico-di-una-capriata\/","title":{"rendered":"Qual \u00e8 lo schema statico di una capriata"},"content":{"rendered":"<p>La capriata, se riceve carichi solo nei nodi e se in questi gli assi degli elementi convergono in uno stesso punto, \u00e8 soggetta a sforzi di <a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"http:\/\/it.wikipedia.org\/wiki\/Trazione_%28fisica%29\">trazione<\/a> (il monaco e soprattutto la catena) o compressione (i puntoni); altrimenti i carichi che gravano sui puntoni generano in essi dei momenti flettenti mentre le eccentricit\u00e0 nei nodi generano dei momenti in ogni membratura ivi convergente. <\/p><p>Non si possono infatti tollerare <b>azioni orizzontali<\/b> che non siano dovute la sisma, perch\u00e9 si creerebbe un <b>effetto cumulativo<\/b> molto dannoso per la stabilit\u00e0 della struttura. <\/p> <h2> <span class=\"mw-headline\" id=\"Collegamenti_esterni\">Collegamenti esterni<\/span><\/h2> <ul><li><a href=\"http:\/\/en.wikipedia.org\/wiki\/it:Capriata\" class=\"extiw\" title=\"wikipedia:it:Capriata\">Wikipedia:it:Capriata<\/a> <\/li><\/ul>  <!-- Tidy found serious XHTML errors -->  <!--  NewPP limit report Preprocessor node count: 3\/1000000 Post-expand include size: 0\/2097152 bytes Template argument size: 0\/2097152 bytes Expensive parser function count: 0\/100 -->  <!-- Saved in parser cache with key wikidb-mw_:pcache:idhash:439-0!*!*!*!*!*!* and timestamp 20130403155656 --> ","protected":false},"excerpt":{"rendered":"<p>La capriata, se riceve carichi solo nei nodi e se in questi gli assi degli elementi convergono in uno stesso punto, \u00e8 soggetta a sforzi di trazione (il monaco e soprattutto la catena) o compressione (i puntoni); altrimenti i carichi che gravano sui puntoni generano in essi dei momenti flettenti mentre le eccentricit\u00e0 nei nodi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[8,9],"class_list":["post-506","post","type-post","status-publish","format-standard","category-w","tag-esame-di-stato-architettura","tag-tecnologia"],"views":16743,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/comments?post=506"}],"version-history":[{"count":0,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/506\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/media?parent=506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/categories?post=506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/tags?post=506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}