{"id":512,"date":"2010-07-23T18:38:00","date_gmt":"2010-07-23T18:38:00","guid":{"rendered":"http:\/\/wiki2.professionearchitetto.it\/quali-sono-i-tipi-dappalto\/"},"modified":"2010-07-23T18:38:00","modified_gmt":"2010-07-23T18:38:00","slug":"quali-sono-i-tipi-dappalto","status":"publish","type":"post","link":"https:\/\/www.professionearchitetto.it\/wiki\/quali-sono-i-tipi-dappalto\/","title":{"rendered":"Quali sono i tipi d&#8217;appalto"},"content":{"rendered":"<p>Si distinguono quattro tipi di appalto: <\/p> <dl><dt>Appalto a corpo o a forfait. <\/dt><dd> Si presenta quando il compenso dell&#8217;imprenditore \u00e8 fissato invariabilmente in base alle parametrazioni risultanti dal contratto, l&#8217;importo totale dell&#8217;opera viene stabilito a monte del progetto, ci\u00f2 significa che a volte per rispettare l&#8217;importo contrattuale si effettuano poche varianti ai lavori durante la loro esecuzione, infatti in caso di modifiche al contratto l&#8217;appalto a corpo non risulta elastico e la direzione dei lavori deve tenere una contabilit\u00e0 in aumento ed una in detrazione rispetto all&#8217;ammontare dell&#8217;importo stabilito.<br\/>Per tale motivo \u00e8 indispensabile una dettagliata elaborazione del progetto esecutivo. \u00c8 l&#8217;appalto preferito dalla committenza privata che si &#8230; da eventuali rischi derivanti da lavori a consuntivo. <\/dd><dt>Appalto a misura. <\/dt><dd> Il credito dell&#8217;imprenditore nell&#8217;appalto a misura viene computato in funzione della quantit\u00e0 di lavoro effettivamente svolto rispetto alle singole categorie di lavori; in base ai singoli prezzi unitari si determina il credito dell&#8217;imprenditore. <\/dd><dt>Lavori in economia <\/dt><dd> Si ha quando il Committente partecipa direttamente all&#8217;esecuzione dell&#8217;opera, assumendo le vesti del Direttore dei Lavori. Viene normalmente usato per lavori di limitata entit\u00e0 e difficolt\u00e0 tali da poter essere gestiti dallo stesso committente che provvede direttamente all&#8217;acquisto dei materiali necessari, al noleggio delle attrezzature, all&#8217;impiego della manodopera. <\/dd><dt>L&#8217;appalto misto <\/dt><dd> \u00e8 una forma di contratto in cui coesistono varie categorie di opere per ciascuna delle quali si stabilisce una differente retribuzione: a corpo, a misura e in economia.<br\/>Si pu\u00f2 avere ad esempio che le strutture di un fabbricato vengano retribuite a corpo &#8220;vuoto per pieno&#8221;, mentre le opere di fondazione vengano valutate a misura. <\/dd><\/dl>  <!-- Tidy found serious XHTML errors -->  <!--  NewPP limit report Preprocessor node count: 3\/1000000 Post-expand include size: 0\/2097152 bytes Template argument size: 0\/2097152 bytes Expensive parser function count: 0\/100 -->  <!-- Saved in parser cache with key wikidb-mw_:pcache:idhash:440-0!*!*!*!*!*!* and timestamp 20130404123403 --> ","protected":false},"excerpt":{"rendered":"<p>Si distinguono quattro tipi di appalto: Appalto a corpo o a forfait. Si presenta quando il compenso dell&#8217;imprenditore \u00e8 fissato invariabilmente in base alle parametrazioni risultanti dal contratto, l&#8217;importo totale dell&#8217;opera viene stabilito a monte del progetto, ci\u00f2 significa che a volte per rispettare l&#8217;importo contrattuale si effettuano poche varianti ai lavori durante la loro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[8,14],"class_list":["post-512","post","type-post","status-publish","format-standard","category-w","tag-esame-di-stato-architettura","tag-esercizio-professionale"],"views":43855,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/comments?post=512"}],"version-history":[{"count":0,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/512\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/media?parent=512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/categories?post=512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/tags?post=512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}