{"id":520,"date":"2010-07-21T11:15:22","date_gmt":"2010-07-21T11:15:22","guid":{"rendered":"http:\/\/wiki2.professionearchitetto.it\/riot-radical-image-optimization-tool\/"},"modified":"2014-03-11T11:58:46","modified_gmt":"2014-03-11T10:58:46","slug":"riot-radical-image-optimization-tool","status":"publish","type":"post","link":"https:\/\/www.professionearchitetto.it\/wiki\/riot-radical-image-optimization-tool\/","title":{"rendered":"RIOT &#8211; Radical Image Optimization Tool"},"content":{"rendered":"<p>Si tratta di un <a class=\"mw-redirect\" title=\"Software Libero\" href=\"\/wiki\/software-libero\">software gratuito<\/a> espressamente dedicato alla ottimizzazione delle immagini per il web. Le funzioni a disposizione sono quelle che servono: rotazione, ridimensionamento e ovviamente tanti tipi di compressione.<\/p>\r\n<p>L&#8217;obiettivo di questo genere di programmi \u00e8 di ridurre al mimino la dimensione del file senza significativi decadimenti dell&#8217;immagine. Il miglior rapporto fra compressione e qualit\u00e0 dell&#8217;immagine.<\/p>\r\n<p>RIOT \u00e8 in grado di aprire file di qualsiasi formato ma salva solamente in formato JPG, GIF o PNG, che sono gli unici formati utilizzabili sul web.<\/p>\r\n<p>La visualizzazione standard prevede la modalit\u00e0 dual view (immagine originale ed ottimizzata).<\/p>\r\n<p><a class=\"image\" href=\"\/wiki\/fileriot-mare-jpg\"><img loading=\"lazy\" decoding=\"async\" alt=\"Riot mare.jpg\" src=\"\/wiki\/images\/e\/ec\/Riot_mare.jpg\" width=\"480\" height=\"390\" \/><\/a><\/p>\r\n<p>Il funzionamento \u00e8 molto semplice ed intuitivo. \u00c8 sufficiente trascinare sul riquadro di sinistra l&#8217;immagine da ottimizzare, per poter vedere le riquadro di destra il risultato ottimizzato oltre al peso in byte del file.<\/p>\r\n<p>Si tratta di un&#8217;applicazione &#8220;portatile&#8221; che pu\u00f2 essere caricata su una chiavetta USB e lanciata all&#8217;occorrenza senza bisogno di installazioni.<\/p>\r\n<p>Sia il livello di compressione che le possibilit\u00e0 di ridimensionamento sono di altissima qualit\u00e0, e sono comparabili a quelle che si possono ottenere con software commerciali (Fireworks o il &#8220;Salva per web&#8221; di Photoshop).<\/p>\r\n<p>RIOT \u00e8 un software libero realizzato da <a class=\"external text\" href=\"http:\/\/luci.criosweb.ro\/riot\/the-author\/\" target=\"_blank\" rel=\"nofollow\"><b>Lucian Sabo<\/b><\/a>, ed \u00e8 scaricabile all&#8217;indirizzo: <a class=\"external free\" href=\"http:\/\/luci.criosweb.ro\/riot\/\" target=\"_blank\" rel=\"nofollow\">http:\/\/luci.criosweb.ro\/riot\/<\/a><\/p>\r\n<p>Ne esiste anche una versione plugin per <a title=\"The GIMP\" href=\"\/wiki\/the-gimp\">GIMP<\/a><\/p>\r\n<p><!-- Tidy found serious XHTML errors --> <!--  NewPP limit report Preprocessor node count: 1\/1000000 Post-expand include size: 0\/2097152 bytes Template argument size: 0\/2097152 bytes Expensive parser function count: 0\/100 --> <!-- Saved in parser cache with key wikidb-mw_:pcache:idhash:398-0!*!0!*!*!2!* and timestamp 20130404013116 --><\/p>","protected":false},"excerpt":{"rendered":"<p>Si tratta di un software gratuito espressamente dedicato alla ottimizzazione delle immagini per il web. Le funzioni a disposizione sono quelle che servono: rotazione, ridimensionamento e ovviamente tanti tipi di compressione. L&#8217;obiettivo di questo genere di programmi \u00e8 di ridurre al mimino la dimensione del file senza significativi decadimenti dell&#8217;immagine. Il miglior rapporto fra compressione [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[38,25,15],"class_list":["post-520","post","type-post","status-publish","format-standard","category-lezioni-web","tag-scrivere-per-il-web","tag-software-grafica","tag-software-libero"],"views":7649,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/comments?post=520"}],"version-history":[{"count":0,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/520\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/media?parent=520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/categories?post=520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/tags?post=520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}