{"id":552,"date":"2011-05-16T06:21:51","date_gmt":"2011-05-16T06:21:51","guid":{"rendered":"http:\/\/wiki2.professionearchitetto.it\/salva-e-riutilizza-i-driver-del-tuo-pc\/"},"modified":"2011-05-16T06:21:51","modified_gmt":"2011-05-16T06:21:51","slug":"salva-e-riutilizza-i-driver-del-tuo-pc","status":"publish","type":"post","link":"https:\/\/www.professionearchitetto.it\/wiki\/salva-e-riutilizza-i-driver-del-tuo-pc\/","title":{"rendered":"Salva e riutilizza i driver del tuo PC"},"content":{"rendered":"<p>WinDriver Expert<b> \u00e8 un programma <\/b>free<b> che permette di salvare i driver del tuo pc senza doverli ricercare su internet o su qualche vecchio cd introvabile.<\/b> <\/p><p>Non necessita di installazione. <\/p><p><a rel=\"nofollow\" target=\"_blank\" class=\"external free\" href=\"http:\/\/www.megalab.it\/articoli.php?id=495\">http:\/\/www.megalab.it\/articoli.php?id=495<\/a> <\/p><p><b>Double Driver<\/b> \u00e8 un utility gratuita che permette di effettuare il backup e anche il successivo ripristino, magari dopo una formattazione, dei drivers installati nel proprio sistema operativo Windows <\/p><p><a rel=\"nofollow\" target=\"_blank\" class=\"external free\" href=\"http:\/\/www.wintricks.it\/news2\/article.php?ID=7768\">http:\/\/www.wintricks.it\/news2\/article.php?ID=7768<\/a> <\/p><p><a rel=\"nofollow\" target=\"_blank\" class=\"external free\" href=\"http:\/\/boozet.xepher.net\/dd\/\">http:\/\/boozet.xepher.net\/dd\/<\/a> <\/p><p>raf <\/p> <!-- Tidy found serious XHTML errors -->  <!--  NewPP limit report Preprocessor node count: 1\/1000000 Post-expand include size: 0\/2097152 bytes Template argument size: 0\/2097152 bytes Expensive parser function count: 0\/100 -->  <!-- Saved in parser cache with key wikidb-mw_:pcache:idhash:506-0!*!*!*!*!*!* and timestamp 20130403162232 --> ","protected":false},"excerpt":{"rendered":"<p>WinDriver Expert \u00e8 un programma free che permette di salvare i driver del tuo pc senza doverli ricercare su internet o su qualche vecchio cd introvabile. Non necessita di installazione. http:\/\/www.megalab.it\/articoli.php?id=495 Double Driver \u00e8 un utility gratuita che permette di effettuare il backup e anche il successivo ripristino, magari dopo una formattazione, dei drivers installati [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-552","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-w"},"views":2630,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/comments?post=552"}],"version-history":[{"count":0,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/552\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/media?parent=552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/categories?post=552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/tags?post=552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}