{"id":560,"date":"2011-05-25T09:01:57","date_gmt":"2011-05-25T09:01:57","guid":{"rendered":"http:\/\/wiki2.professionearchitetto.it\/screenshot\/"},"modified":"2011-05-25T09:01:57","modified_gmt":"2011-05-25T09:01:57","slug":"screenshot","status":"publish","type":"post","link":"https:\/\/www.professionearchitetto.it\/wiki\/screenshot\/","title":{"rendered":"Screenshot"},"content":{"rendered":"<p>Per <b>screenshot<\/b> si intende un&#8217;immagine digitale catturata dallo schermo di un computer, attraverso il sistema operativo o attraverso software specifici, che raffigura il contenuto visibile nel momento dello scatto. <\/p><p>Lo <i>screen capture<\/i> \u00e8 invece la registrazione di tanti singoli screenshots ripetuti nel tempo e uniti in un unico filmato. Tale tecnica \u00e8 molto utile per registrare da fonti altrimenti non accessibili (streaming video) oppure per realizzare <a href=\"\/wiki\/tutorial\" title=\"Tutorial\">tutorial<\/a> video.  <\/p><p>Gli screenshots sono utilizzati in molti campi. Su Internet sono impiegati per realizzare tutorials, per illustrare le funzionalit\u00e0 di programmi, registrare errori o crash, oppure per inviare velocemente via mail informazioni di lavoro (ad esempio la bozza di un render, senza necessariamente elaborare un&#8217;immagine o salvare il file). <\/p><p>Gli screenshot si possono realizzare sia attraverso le funzionalit\u00e0 del sistema operativo adoperato (Microsoft Windows, Mac OS X, ecc.), sia attraverso programmi dedicati. Questi consentono solitamente pi\u00f9 funzionalit\u00e0 come poter ritagliare l&#8217;immagine o salvarla in altri formati. <\/p> <table id=\"toc\" class=\"toc\"><tr><td><div id=\"toctitle\"><h2>Indice<\/h2><\/div> <ul> <li class=\"toclevel-1 tocsection-1\"><a href=\"#Realizzare_uno_screenshot_in_Windows\"><span class=\"tocnumber\">1<\/span> <span class=\"toctext\">Realizzare uno screenshot in Windows<\/span><\/a><\/li> <li class=\"toclevel-1 tocsection-2\"><a href=\"#Realizzare_uno_scrrenshot_in_Mac_OS_X\"><span class=\"tocnumber\">2<\/span> <span class=\"toctext\">Realizzare uno scrrenshot in Mac OS X<\/span><\/a><\/li> <li class=\"toclevel-1 tocsection-3\"><a href=\"#Programmi_per_effettuare_uno_screenshot\"><span class=\"tocnumber\">3<\/span> <span class=\"toctext\">Programmi per effettuare uno screenshot<\/span><\/a><\/li> <li class=\"toclevel-1 tocsection-4\"><a href=\"#Screencast\"><span class=\"tocnumber\">4<\/span> <span class=\"toctext\">Screencast<\/span><\/a><\/li> <li class=\"toclevel-1 tocsection-5\"><a href=\"#Thumbshot\"><span class=\"tocnumber\">5<\/span> <span class=\"toctext\">Thumbshot<\/span><\/a><\/li> <li class=\"toclevel-1 tocsection-6\"><a href=\"#Collegamenti_esterni\"><span class=\"tocnumber\">6<\/span> <span class=\"toctext\">Collegamenti esterni<\/span><\/a><\/li> <\/ul> <\/td><\/tr><\/table> <h2> <span class=\"mw-headline\" id=\"Realizzare_uno_screenshot_in_Windows\">Realizzare uno screenshot in Windows<\/span><\/h2> <p>In Windows \u00e8 possibile effettuare uno scrrenshot dell&#8217;intera schermata attraverso la pressione del pulsante della tastiera <i>Stamp | R Sist (<b>STAMP<\/b>)<\/i>. L&#8217;immagine verr\u00e0 depositata nella clipboard (gli appunti). Sar\u00e0 quindi necessario aprire un programma come Paint e incollare l&#8217;immagine all&#8217;interno di un file attraverso la pressione di <i><b>CTRL+V<\/b><\/i>.  <\/p><p>Attraverso <i><b>ALT+STAMP<\/b><\/i> \u00e8 possibile effettuare lo scrrenshot limitato alla fienstra di lavoro in quel momento attiva.  <\/p> <h2> <span class=\"mw-headline\" id=\"Realizzare_uno_scrrenshot_in_Mac_OS_X\">Realizzare uno scrrenshot in Mac OS X<\/span><\/h2> <p>Sotto Mac OS X di Apple le combinazioni di tasti sono le seguenti: <i><b>Command + Shift + 3<\/b><\/i> per la schermata intera, <i><b>Command + Shift + 4<\/b><\/i>, per una regione limitata dello schermo. In quest&#8217;ultimo caso, trascinando il cursore, si potr\u00e0 selezionare l&#8217;ampiezza dell&#8217;area da salvare. Nel momento dello scatto, si sentir\u00e0 il rumore di una macchina fotografica. Le immagini vengono salvate direttamente sulla scrivania. <\/p> <h2> <span class=\"mw-headline\" id=\"Programmi_per_effettuare_uno_screenshot\">Programmi per effettuare uno screenshot<\/span><\/h2> <p>Esistono numerosi programmi, per ogni sistema operativo, in grado di effettuare screenshot pi\u00f9 o meno complessi. Le differenze pi\u00f9 evidenti si hanno su alcune opzioni come quelle di salvataggio in vari formati, sul timing dello scatto, sulla possibilit\u00e0 di realizzare filmati. <\/p> <h2> <span class=\"mw-headline\" id=\"Screencast\">Screencast<\/span><\/h2> <p>Uno <i>screencast<\/i> \u00e8 una registrazione digitale, sotto forma di filmato, della\u00a0 schermata di un computer compreso, se desiderato, l&#8217;audio.Gli screencast sono molto utilizzati sia per l&#8217;insegnamento sia per la dimostrazione delle specifiche dei software.\u00a0  <\/p> <h2> <span class=\"mw-headline\" id=\"Thumbshot\">Thumbshot<\/span><\/h2> <p>I <i>thumbshot<\/i> sono degli screenshot di documenti online e di siti web in piccole dimensioni, solitamente 120X90 pixels. Sono usati per facilitare la navigazione in siti web o come preview.  <\/p> <h2> <span class=\"mw-headline\" id=\"Collegamenti_esterni\">Collegamenti esterni<\/span><\/h2> <ul><li><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"http:\/\/it.wikipedia.org\/wiki\/Screenshot\">it.wikipedia.org<\/a>, voce Screenshot <\/li><\/ul> <ul><li><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"http:\/\/en.wikipedia.org\/wiki\/List_of_screen_recording_software\">en.wikipedia.org<\/a>, List of screen recording software <\/li><\/ul> <ul><li><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"http:\/\/www.macdevcenter.com\/pub\/a\/mac\/2003\/02\/28\/screenshot.html\">Screenshot Hacks for Mac OS X<\/a> <\/li><\/ul> <ul><li><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"http:\/\/digitalmedia.oreilly.com\/2006\/01\/01\/mac-os-x-screenshot-secrets.html\">Mac OS X Screenshot Secrets<\/a> <\/li><\/ul>  <!-- Tidy found serious XHTML errors -->  <!--  NewPP limit report Preprocessor node count: 23\/1000000 Post-expand include size: 0\/2097152 bytes Template argument size: 0\/2097152 bytes Expensive parser function count: 0\/100 -->  <!-- Saved in parser cache with key wikidb-mw_:pcache:idhash:646-0!*!0!!it!*!* and timestamp 20130403155105 --> ","protected":false},"excerpt":{"rendered":"<p>Per screenshot si intende un&#8217;immagine digitale catturata dallo schermo di un computer, attraverso il sistema operativo o attraverso software specifici, che raffigura il contenuto visibile nel momento dello scatto. Lo screen capture \u00e8 invece la registrazione di tanti singoli screenshots ripetuti nel tempo e uniti in un unico filmato. Tale tecnica \u00e8 molto utile per [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-560","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-w"},"views":13744,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/comments?post=560"}],"version-history":[{"count":0,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/560\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/media?parent=560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/categories?post=560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/tags?post=560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}