{"id":610,"date":"2011-05-16T06:40:13","date_gmt":"2011-05-16T06:40:13","guid":{"rendered":"http:\/\/wiki2.professionearchitetto.it\/suggerimenti-per-autocad-da-classificare\/"},"modified":"2011-05-16T06:40:13","modified_gmt":"2011-05-16T06:40:13","slug":"suggerimenti-per-autocad-da-classificare","status":"publish","type":"post","link":"https:\/\/www.professionearchitetto.it\/wiki\/suggerimenti-per-autocad-da-classificare\/","title":{"rendered":"Suggerimenti per AutoCAD &#8211; da classificare"},"content":{"rendered":"<p>c&#8217;\u00e8 ancora da fare: <\/p><p><a href=\"\/wiki\/autocad-comandi-non-documentati\" title=\"AutoCAD - Comandi non documentati\">AutoCAD &#8211; Comandi non documentati<\/a> <\/p><p><a href=\"\/wiki\/autocad-pan-ortogonale-e-zoomfactor\" title=\"AutoCAD - Pan ortogonale e ZOOMFACTOR\">AutoCAD &#8211; Pan ortogonale e ZOOMFACTOR<\/a> <\/p><p><a href=\"\/wiki\/autocad-trucchi-e-scorciatoie\" title=\"AutoCAD - Trucchi e Scorciatoie\">AutoCAD &#8211; Trucchi e Scorciatoie<\/a> <\/p><p><a href=\"\/wiki\/autocad-tutti-i-comandi-e-le-variabili\" title=\"AutoCAD - Tutti i Comandi e le Variabili\">AutoCAD &#8211; Tutti i Comandi e le Variabili<\/a> <\/p><p><a href=\"\/wiki\/autocad-alleggerire-dwg-in-automatico\" title=\"AutoCAD - Alleggerire dwg in automatico\">AutoCAD &#8211; Alleggerire dwg in automatico<\/a> <\/p><p><a href=\"\/wiki\/creapagina.php?title=AutoCAD_-_fumetto_di_revisione\" class=\"new\" title=\"AutoCAD - fumetto di revisione (la pagina non esiste)\">AutoCAD &#8211; fumetto di revisione<\/a>, <a href=\"\/wiki\/bubble-per-autocad\" title=\"BUBBLE per AutoCAD\">BUBBLE per AutoCAD<\/a> <\/p><p><a href=\"\/wiki\/autocad-il-file-con-estensione-dwl\" title=\"AutoCAD - il file con estensione .DWL\">AutoCAD &#8211; il file con estensione .DWL<\/a> <\/p><p><a href=\"\/wiki\/creapagina.php?title=AutoCAD_-_modifica_%22dinamica%22_di_LTSCALE\" class=\"new\" title=\"AutoCAD - modifica &quot;dinamica&quot; di LTSCALE (la pagina non esiste)\">AutoCAD &#8211; modifica &#8220;dinamica&#8221; di LTSCALE<\/a> <\/p><p><a href=\"\/wiki\/creapagina.php?title=AutoCAD_-_proteggere_DWG_da_modifiche\" class=\"new\" title=\"AutoCAD - proteggere DWG da modifiche (la pagina non esiste)\">AutoCAD &#8211; proteggere DWG da modifiche<\/a> <\/p><p><a href=\"\/wiki\/creapagina.php?title=AutoCAD_-_visualizza_%2B_nomi_nelle_tendine\" class=\"new\" title=\"AutoCAD - visualizza + nomi nelle tendine (la pagina non esiste)\">AutoCAD &#8211; visualizza + nomi nelle tendine<\/a> <\/p><p><a href=\"\/wiki\/cercare-dwg-nel-web\" title=\"Cercare DWG nel web\">Cercare DWG nel web<\/a> <\/p><p><a href=\"\/wiki\/come-trasferire-una-licenza-autocad\" title=\"Come trasferire una licenza AutoCAD\">Come trasferire una licenza AutoCAD<\/a> <\/p><p><a href=\"\/wiki\/copia-incolla-con-sfondo-trasparente\" title=\"Copia incolla con sfondo trasparente\">Copia incolla con sfondo trasparente<\/a> <\/p><p><a href=\"\/wiki\/creapagina.php?title=Corso_base_di_autocad_on_line\" class=\"new\" title=\"Corso base di autocad on line (la pagina non esiste)\">Corso base di autocad on line<\/a> <\/p><p><a href=\"\/wiki\/tutorial-su-autocad-on-line\" title=\"Tutorial su AutoCAD on line\">Tutorial su AutoCAD on line<\/a> <\/p><p><a href=\"\/wiki\/dwg-creati-con-versioni-educative-autocad\" title=\"DWG creati con versioni EDUCATIVE AutoCAD\">DWG creati con versioni EDUCATIVE AutoCAD<\/a> <\/p><p><a href=\"\/wiki\/differenzia-le-icone-dei-dwg-autocad\" title=\"Differenzia le icone dei dwg AutoCAD\">Differenzia le icone dei dwg AutoCAD<\/a> <\/p><p><a href=\"\/wiki\/editor-di-icone-free\" title=\"Editor di icone free\">Editor di icone free<\/a> <\/p><p><a href=\"\/wiki\/eliminare-entit%c3%a0-identiche-sovrapposte\" title=\"Eliminare entit\u00e0 identiche sovrapposte\">Eliminare entit\u00e0 identiche sovrapposte<\/a> <\/p><p><a href=\"\/wiki\/forum-dedicati-ad-architectural-desktop\" title=\"Forum dedicati ad Architectural Desktop\">Forum dedicati ad Architectural Desktop<\/a>, <a href=\"\/wiki\/forum-dedicati-ad-autocad\" title=\"Forum dedicati ad AutoCAD\">Forum dedicati ad AutoCAD<\/a>, <a href=\"\/wiki\/creapagina.php?title=Link_Utili:_Manuali_Autocad\" class=\"new\" title=\"Link Utili: Manuali Autocad (la pagina non esiste)\">Link Utili: Manuali Autocad<\/a>, <a href=\"\/wiki\/tutorial-caad\" title=\"Tutorial CAAD\">Tutorial CAAD<\/a> <\/p><p><a href=\"\/wiki\/manina-pan-con-rotellina-mouse-e-zoom-e\" title=\"Manina Pan con rotellina mouse e Zoom E\">Manina Pan con rotellina mouse e Zoom E<\/a> <\/p><p><a href=\"\/wiki\/ordina-la-visualizzazione-degli-oggetti\" title=\"Ordina la visualizzazione degli oggetti\">Ordina la visualizzazione degli oggetti<\/a> <\/p><p><a href=\"\/wiki\/traduzioni-autocad-da-inglese-a-italiano\" title=\"Traduzioni AutoCAD da Inglese a Italiano\">Traduzioni AutoCAD da Inglese a Italiano<\/a> <\/p><p><a href=\"\/wiki\/velocizzare-l%27avvio-di-autocad\" title=\"Velocizzare l'avvio di AutoCAD\">Velocizzare l&#8217;avvio di AutoCAD<\/a> <\/p><p><a href=\"\/wiki\/creapagina.php?title=Finestra_startup_in_autocad_2004_-_2005\" class=\"new\" title=\"Finestra startup in autocad 2004 - 2005 (la pagina non esiste)\">finestra startup in autocad 2004 &#8211; 2005<\/a> <\/p><p><a href=\"\/wiki\/ruotare-contenuto-finestra\" title=\"Ruotare contenuto finestra\">ruotare contenuto finestra<\/a> <\/p><p><a href=\"\/wiki\/un-cad-2d-3d-free\" title=\"Un CAD 2d 3d free\">un CAD 2d 3d free<\/a>, <a href=\"\/wiki\/programma-free-con-24-utilit%c3%a0-per-autocad\" title=\"Programma free con 24 utilit\u00e0 per AutoCAD\">Programma free con 24 utilit\u00e0 per AutoCAD<\/a> <\/p> <!-- Tidy found serious XHTML errors -->  <!--  NewPP limit report Preprocessor node count: 1\/1000000 Post-expand include size: 0\/2097152 bytes Template argument size: 0\/2097152 bytes Expensive parser function count: 0\/100 -->  <!-- Saved in parser cache with key wikidb-mw_:pcache:idhash:511-0!*!0!*!*!*!* and timestamp 20130404090432 --> ","protected":false},"excerpt":{"rendered":"<p>c&#8217;\u00e8 ancora da fare: AutoCAD &#8211; Comandi non documentati AutoCAD &#8211; Pan ortogonale e ZOOMFACTOR AutoCAD &#8211; Trucchi e Scorciatoie AutoCAD &#8211; Tutti i Comandi e le Variabili AutoCAD &#8211; Alleggerire dwg in automatico AutoCAD &#8211; fumetto di revisione, BUBBLE per AutoCAD AutoCAD &#8211; il file con estensione .DWL AutoCAD &#8211; modifica &#8220;dinamica&#8221; di LTSCALE [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-610","post","type-post","status-publish","format-standard","category-w"],"views":5324,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/comments?post=610"}],"version-history":[{"count":0,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/610\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/media?parent=610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/categories?post=610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/tags?post=610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}