{"id":677,"date":"2012-11-03T09:51:12","date_gmt":"2012-11-03T09:51:12","guid":{"rendered":"http:\/\/wiki2.professionearchitetto.it\/tutorial-autocad-come-risolvere-problemi-di-apertura-dei-file-dwg-e-dxf\/"},"modified":"2012-11-03T09:51:12","modified_gmt":"2012-11-03T09:51:12","slug":"tutorial-autocad-come-risolvere-problemi-di-apertura-dei-file-dwg-e-dxf","status":"publish","type":"post","link":"https:\/\/www.professionearchitetto.it\/wiki\/tutorial-autocad-come-risolvere-problemi-di-apertura-dei-file-dwg-e-dxf\/","title":{"rendered":"Tutorial AutoCAD, Come risolvere problemi di apertura dei file DWG e DXF"},"content":{"rendered":"<p>Visto che Raf mi ha invitato a riesumare un mio vecchio thread ed ai suoi inviti giustamente non ci si pu\u00f2 sottrarre vado a riprendere una serie di consigli che possono tornare utili in caso di errori nei file dwg\/dxf di AutoCAD. <\/p><p>Tempo addietro mi era infatti capitato lo spiacevole inconveniente di avere un disegno contenente una progetto composto da solidi 3D in cui avevo riscontrato alcuni problemi aprendo il file. <\/p><p>Inizialmente i problemi sono stati risolti utilizzando la classica opzione \u00f4recupera\u00f6 (_recover) ma poi mi \u00e8 risulta impossibile accedere al file anche utilizzando questa modalit\u00e0. <br style=\"\"\/><br style=\"\"\/> <\/p><p>In pratica succedeva che il file veniva caricato al 93% e poi appariva il seguente messaggio di errore:  <\/p> <hr \/> <p><b>Errore di AutoCAD &#8211; Operazione interrotta<\/b> con la scritta <b>ERRORE INTERNO:&#160;!saveres.cpp<\/b>at440: eGeneralModelingFailure<b> <\/b> <\/p><p>Contemporaneamente nella <b>Finestra di testo AutoCAD<\/b> viene visualizzata quest&#8217;altra scritta:  <\/p><p><b>Caricamento del Modeler delle DLL in corso. <\/b> <\/p><p>Errore operazione di modellazione:  <\/p><p>Intero mancante nel file di ripristino<b><\/b> <\/p><p><br \/> <b>Se anche a Voi dovesse capitare di incorrere in problemi di questo genere o comunque generalmente in problemi legati all&#8217;apertura dei file dwg\/dxf innanzitutto un primo consiglio che potr\u00e0 sembrare banale ma \u00e8 di fondamentale importanza ovvero copiate il file ed effettuare tutte le prove sulle copie avendo l&#8217;accortezza di mantenere l&#8217;originale inalterato per evitare di incasinarlo ancora pi\u00f9 di quanto lo sia gi\u00e0.<\/b> <\/p><p>Poi procedete con questi tentativi::  <\/p><p>1) tentate di aprire il disegno da un altro PC sempre dotato della medesima versione di AutoCAD o di una versione successiva a quella del dwg\/dxf <\/p><p>(a volte pu\u00f2 essere utile anche la versione immediatamente precedente; ad esempio in caso di problemi con un file di Autocad 2006 si pu\u00f2 tentare un recover con il 2005 o il 2004. Lo stesso discorso vale con il 2002 e il 2000) <\/p><p>2) rinominate i file di autosalvataggio sv$ e bak in dwg e tentate di aprirli ( ad esempio con AutoCAD2004 la cartella in cui ricercare i file sv$ la potete individuare digitando _options e nella finestra che appare cliccare sull&#8217;etichetta File e li potete individuare il percorso come indicato nella seguente figura) <\/p><p><img decoding=\"async\" src=\"\/wiki\/images\/uploads\/DnimErrore01.jpg\" alt=\"DnimErrore01.jpg\" \/> <\/p><p>3) aprite un disegno vuoto ed inserite come blocco il file dwg\/dxf che vi dava errore (per inserire i blocchi utilizzate _insert) nb: se avete dei layot utilizzando _insert andranno persi <\/p><p>4) scaricate dal sito Autodesk il software <b>Batch Drawing Converter<\/b> o analogo software che dovesse essere disponibile ed utilizzabile con la Vs. versione di AutoCAD e convertite il file in un altro formato ammissibili. Ad esempio a me era capitato che il software di conversione ha visualizzato un messaggio di errore ma ha comunque effettuato la conversione creando un file che \u00e8 per\u00f2 risultato impossibile da aprire sia con AutoCAD2004 che con AutoCAD200LT. Fortunatamente poi Raf mi ha risolto il problema provando ad utilizzare il comando <b>recupera<\/b> (_recover) a cui non avevo pi\u00f9 pensato visto che era stata la prima cosa che avevo fatto con il file <b>originale<\/b>. <\/p><p>5) come estremo tentativo editate il file dwg con il \u00f4Blocco note\u00f6 sostituendo manualmente una stringa di testo, questa operazione in alcuni casi genera un errore diverso da quello che impedisce l&#8217; apertura del file e permette di caricare almeno parzialmente il disegno. <\/p><p>Per prevenire questi problemi Vi riporto anche alcuni consigli che naturalmente non sono farina del mio sacco ma me li ha segnalati Raf, con questi settaggi dovrebbe essere pi\u00f9 difficile incorrere in problemi del genere:  <\/p><p>1) Attivare l&#8217; opzione convalida CRC continua (digitare _options e cliccare sull&#8217;etichetta visualizzazione vedete immagine seguente)<b><\/b> <\/p><p><img decoding=\"async\" src=\"\/wiki\/images\/uploads\/DnimErrore02.jpg\" alt=\"DnimErrore02.jpg\" \/> <\/p><p>2) Settare INDEXCTL = 3 (Controlla che gli indici spaziali e dei layer vengono creati e salvati nei file di disegno, per impostare la variabile digitare _setvar e poi digitare INDEXCTL ) <\/p><p>3) Settare ISAVEPERCENT = 0 (viene sempre eseguito il salvataggio completo, sempre con il comando _setvar) <\/p><p>Se ad esempio vi interessava effettivamente sapere a cosa corrispondono i diversi valori che si possono assegnare alla variabile INDEXCTL ho estratto dalla guida in linea di AutoCAD i seguendi stralci: <\/p><p><br \/> <\/p> <hr \/> <p>Indica se il file di disegno selezionato contiene un indice spaziale o layer. INDEXCTL controlla se gli indici spaziali o layer vengono salvati con il file di disegno. Un indice spaziale ordina gli oggetti in base alla relativa posizione nello spazio. Un indice per layer \u00e8 costituito da un elenco in cui viene indicato il contenuto dei diversi layer. <\/p><p>Controlla se gli indici spaziali e dei layer vengono creati e salvati nei file di disegno. <\/p><p>0 Non viene creato alcun indice.  <\/p><p>1 Viene creato l&#8217;indice dei layer.  <\/p><p>2 Viene creato l&#8217;indice spaziale.  <\/p><p>3 Vengono creati l&#8217;indice dei layer e l&#8217;indice spaziale <\/p><p>Usa indice spaziale  <\/p><p>Indica se all&#8217;apertura parziale di un disegno AutoCAD utilizza un indice spaziale per individuare la parte di disegno da caricare. Ci\u00f2 consente di ridurre il tempo necessario per l&#8217;apertura del disegno. Se un disegno non contiene un indice spaziale, questa opzione non \u00e8 disponibile.  <\/p><p>Indice spaziale  <\/p><p>Indica se il file di disegno selezionato contiene un indice spaziale, che consente di organizzare gli oggetti in base alla rispettiva posizione nello spazio. Quando si apre un disegno parzialmente, AutoCAD utilizza un indice spaziale per individuare la parte del disegno da caricare. Ci\u00f2 consente di ridurre il tempo necessario per l&#8217;apertura del disegno. <\/p><p>Indice layer  <\/p><p>Indica se il file di disegno selezionato contiene un indice per layer, ovvero un elenco in cui sono riportati gli oggetti posizionati su ciascun layer. Quando si apre un disegno parzialmente, AutoCAD utilizza un indice per layer per individuare la parte di disegno da caricare. Ci\u00f2 consente di ridurre il tempo necessario per l&#8217;apertura del disegno. <\/p> <hr \/> <p><br \/> Per concludere un altro consiglio banale impostate anche l&#8217;autosalvataggio di AutoCAD ad una scadenza temporale sufficientemente ravvicinata, diciamo 15 o 20 minuti, cosi massimo recuperando il file sv$ perderete gli ultimi 20 minuti di lavoro <\/p><p>Se avete anche Voi consigli in merito all&#8217;argomento segnalateli visto che posso sempre fare comodo. <\/p><p>Ps. i thread che avevo aperto al momento disponibili ai seguenti link: <\/p><p><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"http:\/\/www.professionearchitetto.it\/software\/risposte.asp?id=14975\"><b>http:\/\/www.professionearchitetto.it\/software\/risposte.asp?id=14975<\/b><\/a> <\/p><p><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"http:\/\/www.cad3d.it\/modules.php?op=modload&amp;name=XForum&amp;file=viewthread&amp;tid=5198#pid19414\"><b>http:\/\/www.cad3d.it\/modules.php?op=modload&amp;name=XForum&amp;file=viewthread&amp;tid=5198#pid19414<\/b><\/a> <\/p><p><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"http:\/\/www.cadlandia.com\/forum\/topic.asp?TOPIC_ID=2718&amp;SearchTerms=errore\"><b>http:\/\/www.cadlandia.com\/forum\/topic.asp?TOPIC_ID=2718&amp;SearchTerms=errore<\/b><\/a> <\/p><p><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"http:\/\/www.cadlandia.com\/forum\/topic.asp?TOPIC_ID=2748&amp;SearchTerms=errore\"><b>http:\/\/www.cadlandia.com\/forum\/topic.asp?TOPIC_ID=2748&amp;SearchTerms=errore<\/b><\/a> <\/p><p>Ciao. <\/p><p>Aggiungo quest&#8217;altro trucco che ha segnalato tagio nel forum di ProfessioneArchitetto <\/p><p>tagio: DXF (24\/11\/2004) <\/p><p>Prova con il DXF.  <\/p><p>Appena apri AutoCAD con ESC interrompi la rigenerazione del disegno.  <\/p><p>Se questo funziona ti dovrebbero comparire qualche entita&#8217; e il prompt normale dei comandi.  <\/p><p>A questo punto dai il comando DXFOUT per creare un file .DXF (puoi anche cercare nel file l&#8217;errore, ma e un po difficile)  <\/p><p>Apri un nuovo disegno e dai il comando DXFIN, ti chiede il nome del file DXF ecc. ecc.  <\/p><p>Buona Fortuna <b><\/b> <\/p><p><br \/> Aggiungo quest&#8217;altro&#8221;trucco&#8221;che ha segnalato Raf nel forum di ProfessioneArchitetto <\/p><p><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"http:\/\/www.professionearchitetto.it\/bacheca\/risposte.asp?id=40432\"><b>http:\/\/www.professionearchitetto.it\/bacheca\/risposte.asp?id= 40432<\/b><\/a> <\/p><p>In pratica il software Batch Drawing Converter non \u00e8 risultato utile MA in parte \u00e8 stato possibile recuperare i file utilizzando un software alternativo, eccovi quanto ha scritto Raf in un paio di suoi interventi: <\/p><p>raf: x geoPadova (26\/01\/2005) <\/p><p>ti ho inviato il dwg,  <\/p><p>purtroppo non si riesce a recuperare,  <\/p><p>le uniche parti salvate le ho ottenute usando CADVER  <\/p><p><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"http:\/\/www.professionearchitetto.it\/software\/topic.asp?id=148\"><b>http:\/\/www.professionearchitetto.it\/software\/topic.asp?id=148<\/a><\/b> <\/p><p><br \/> <b>CAD Version Converter<\/b> \u00e8 un programma free che permette di convertire dwg e dxf AutoCAD dalla versione 2005 sino alla versione R13. <\/p><p>\u00c8 indipendente, <i>non ha bisogno della presenza di AutoCAD<\/i> sul computer. <\/p><p><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"http:\/\/ftp.surfnet.nl\/simtel\/win95\/cad\/cadver.exe\"><b>http:\/\/ftp.surfnet.nl\/simtel\/win95\/cad\/cadver.exe<\/b><\/a> <\/p><p>Per chi ha ancora una versione 14 di AutoCAD ed avesse problemi con dei disegni potrebbe essere utile scaricarsi la patch satfixer.exe che corregge dei bug noti, il link \u00e8 questo: <\/p><p><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"http:\/\/usa.autodesk.com\/adsk\/servlet\/ps\/dl\/item?siteID=12311\">2&amp;id=2523543&amp;linkID=2475161  http:\/\/usa.autodesk.com\/adsk\/servlet\/ps\/dl\/item?siteID=12311 2&amp;id=2523543&amp;linkID=2475161<\/a> <\/p><p>L&#8217;errore generalmente viene segnalato con questo messaggio: <\/p><p>ACIS error 61006 Missing double in restore file <\/p><p><br \/> Un altra possibile causa di problemi con i dwg\/dxf pu\u00f2 essere un incompatibilit\u00e0 con l&#8217;antivirus. <\/p><p>Ad esempio il seguente messaggio di errore \u00e8 stato risolto cambiando l&#8217;antivirus: <\/p><p>Internal Error:&#160;!U:globalincdbqspace.h@386: eDwgObjectImproperklyRead <\/p><p>Per maggiori info potete vedere questo link: <\/p><p><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"http:\/\/www.cadlandia.com\/forum\/topic.asp?TOPIC_ID=4491\"><b>http:\/\/www.cadlandia.com\/forum\/topic.asp?TOPIC_ID=4491<\/b><\/a> <\/p><p><br \/> dnim, dnim, dnim, dnim, dnim, simpho <\/p> <!-- Tidy found serious XHTML errors -->  <!--  NewPP limit report Preprocessor node count: 3\/1000000 Post-expand include size: 0\/2097152 bytes Template argument size: 0\/2097152 bytes Expensive parser function count: 0\/100 -->  <!-- Saved in parser cache with key wikidb-mw_:pcache:idhash:427-0!*!*!*!*!*!* and timestamp 20130404070854 --> ","protected":false},"excerpt":{"rendered":"<p>Visto che Raf mi ha invitato a riesumare un mio vecchio thread ed ai suoi inviti giustamente non ci si pu\u00f2 sottrarre vado a riprendere una serie di consigli che possono tornare utili in caso di errori nei file dwg\/dxf di AutoCAD. Tempo addietro mi era infatti capitato lo spiacevole inconveniente di avere un disegno [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[18,33],"class_list":["post-677","post","type-post","status-publish","format-standard","category-w","tag-tutorial","tag-tutorial-autocad"],"views":130101,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/comments?post=677"}],"version-history":[{"count":0,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/677\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/media?parent=677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/categories?post=677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/tags?post=677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}