{"id":739,"date":"2011-05-17T11:14:26","date_gmt":"2011-05-17T09:14:26","guid":{"rendered":"http:\/\/wiki2.professionearchitetto.it\/vespaio\/"},"modified":"2015-07-19T17:53:09","modified_gmt":"2015-07-19T15:53:09","slug":"vespaio","status":"publish","type":"post","link":"https:\/\/www.professionearchitetto.it\/wiki\/vespaio\/","title":{"rendered":"Vespaio"},"content":{"rendered":"<h2> <span class=\"mw-headline\" id=\"Che_funzione_ha_e_come_.C3.A8_fatto_il_vespaio\">Che funzione ha e come \u00e8 fatto il vespaio<\/span><\/h2> <p>Il <b>vespaio<\/b> \u00e8 uno dei sistemi pi\u00f9 semplici di protezione dall&#8217;umidit\u00e0 che si possono prevedere negli attacchi a terra degli edifici per assicurare che l&#8217;acqua contenuta nel terreno non si infiltri nelle strutture a diretto contatto con esso o non renda umidi i locali seminterrati o interrati. <\/p><p>Lo spessore del vespaio per le superfici orizzontali deve essere di circa 30-35 cm, per le superfici verticali si fa uno scavo nel terreno dalla quota di campagna fino alla quota di imposta della fondazione, si getta una cunetta di raccolta in c.a. con adeguata pendenza per lo smaltimento delle acque infiltrate e si assestano a mano pezzami di pietra a ridosso delle murature. <\/p><p>La muratura, prima della realizzazione del vespaio, pu\u00f2 essere trattata con una mano di catramina o impermeabilizzata con una guaina di bitume. <\/p><p>Con un vespaio ventilato si diluisce anche la percentuale di radon (gas radioattivo) che dal terreno arriva ai locali abitati. <\/p> <h2> <span class=\"mw-headline\" id=\"Collegamenti_esterni\">Collegamenti esterni<\/span><\/h2> <p><a rel=\"nofollow\" target=\"_blank\" class=\"external text\" href=\"http:\/\/www.costruireabitaresano.it\/news\/solai_controterra.htm\">www.costruireabitaresano.it\/news\/solai_controterra.htm<\/a> <\/p> <!-- Tidy found serious XHTML errors -->  <!--  NewPP limit report Preprocessor node count: 6\/1000000 Post-expand include size: 0\/2097152 bytes Template argument size: 0\/2097152 bytes Expensive parser function count: 0\/100 -->  <!-- Saved in parser cache with key wikidb-mw_:pcache:idhash:135-0!*!*!!*!*!* and timestamp 20130404074209 --> ","protected":false},"excerpt":{"rendered":"<p>Che funzione ha e come \u00e8 fatto il vespaio Il vespaio \u00e8 uno dei sistemi pi\u00f9 semplici di protezione dall&#8217;umidit\u00e0 che si possono prevedere negli attacchi a terra degli edifici per assicurare che l&#8217;acqua contenuta nel terreno non si infiltri nelle strutture a diretto contatto con esso o non renda umidi i locali seminterrati o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[3,8,59,9],"class_list":["post-739","post","type-post","status-publish","format-standard","category-w","tag-archibolario","tag-esame-di-stato-architettura","tag-fisica-tecnica","tag-tecnologia"],"views":34005,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/comments?post=739"}],"version-history":[{"count":0,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/739\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/media?parent=739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/categories?post=739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/tags?post=739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}