{"id":9,"date":"2010-06-09T07:34:12","date_gmt":"2010-06-09T07:34:12","guid":{"rendered":"http:\/\/wiki2.professionearchitetto.it\/abilitare-il-prompt-contestuale\/"},"modified":"2010-06-09T07:34:12","modified_gmt":"2010-06-09T07:34:12","slug":"abilitare-il-prompt-contestuale","status":"publish","type":"post","link":"https:\/\/www.professionearchitetto.it\/wiki\/abilitare-il-prompt-contestuale\/","title":{"rendered":"Abilitare il prompt contestuale"},"content":{"rendered":"<p>un pratico registro che permette di lanciare il prompt direttamente dalla cartella corrente, senza bisogno di dover digitare il percorso da tastiera <\/p><p><a rel=\"nofollow\" target=\"_blank\" class=\"external free\" href=\"http:\/\/www.megalab.it\/articoli.php?id=521\">http:\/\/www.megalab.it\/articoli.php?id=521<\/a> <\/p><p>raf <\/p> <!-- Tidy found serious XHTML errors -->  <!--  NewPP limit report Preprocessor node count: 1\/1000000 Post-expand include size: 0\/2097152 bytes Template argument size: 0\/2097152 bytes Expensive parser function count: 0\/100 -->  <!-- Saved in parser cache with key wikidb-mw_:pcache:idhash:24-0!*!*!*!*!*!* and timestamp 20130404085719 --> ","protected":false},"excerpt":{"rendered":"<p>un pratico registro che permette di lanciare il prompt direttamente dalla cartella corrente, senza bisogno di dover digitare il percorso da tastiera http:\/\/www.megalab.it\/articoli.php?id=521 raf<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9","post","type-post","status-publish","format-standard","category-w"],"views":1869,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":0,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/posts\/9\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/media?parent=9"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/categories?post=9"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.professionearchitetto.it\/wiki\/wp-json\/wp\/v2\/tags?post=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}